{"id":8833,"date":"2018-04-03T10:42:03","date_gmt":"2018-04-03T07:42:03","guid":{"rendered":"http:\/\/test3.aenima.grproduct\/vibrateurs-electriques-a-haute-frequence\/"},"modified":"2018-04-03T10:42:03","modified_gmt":"2018-04-03T07:42:03","slug":"vibrateurs-electriques-a-haute-frequence","status":"publish","type":"product","link":"https:\/\/abcon.gr\/fr\/produit\/vibrateurs-electriques-a-haute-frequence\/","title":{"rendered":"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Sur les chantiers de pr\u00e9fabrication, pour obtenir une finition impeccable des \u00e9l\u00e9ments en b\u00e9ton \u00e0 r\u00e9sistance tr\u00e8s \u00e9lev\u00e9e, la vibration \u00e0 haute fr\u00e9quence est une n\u00e9cessit\u00e9 absolue.<br \/>\nNous vous proposons des vibrateurs \u00e9lectriques \u00e0 moteur asynchrone triphas\u00e9, support\u00e9s par une robuste ossature et assembl\u00e9s pour une protection IP 65.7.<br \/>\nDisponibles avec fixation \u00e0 plaque ou \u00e0 berceau.<br \/>\nLes vibrateurs s\u00e9rie AFC et AFP \u00e0 haute fr\u00e9quence ou \u00e0 fr\u00e9quence de r\u00e9seau sont utilis\u00e9s sur les coffrages ou les tables vibrantes pour la r\u00e9alisation d\u2019\u00e9l\u00e9ments en b\u00e9ton<\/p>\n<p>\u2022\u00a0ALIMENTATION TRIPHASEE<\/p>\n<p>Sur demande, Bianchi Casseforme peut fournir le convertisseur de fr\u00e9quence ad\u00e9quat pour le fonctionnement de ses propres vibrateurs.<\/p>\n","protected":false},"featured_media":6518,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[214,239,247],"product_tag":[325],"class_list":["post-8833","product","type-product","status-publish","has-post-thumbnail","product_cat-equipement-precast","product_cat-vibrateurs","product_cat-vibrations-electiques","product_tag-bianchi-fr","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence - A.B.CON.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abcon.gr\/produit\/\u03b7\u03bb\u03b5\u03ba\u03c4\u03c1\u03b9\u03ba\u03bf\u03c3-\u03b4\u03bf\u03bd\u03b7\u03c4\u03b7\u03c3-\u03c5\u03c8\u03b7\u03bb\u03b7\u03c3-\u03c3\u03c5\u03c7\u03bd\u03bf\u03c4\u03b7\u03c4\u03b1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence - A.B.CON.\" \/>\n<meta property=\"og:description\" content=\"Sur les chantiers de pr\u00e9fabrication, pour obtenir une finition impeccable des \u00e9l\u00e9ments en b\u00e9ton \u00e0 r\u00e9sistance tr\u00e8s \u00e9lev\u00e9e, la vibration \u00e0 haute fr\u00e9quence est une n\u00e9cessit\u00e9 absolue. Nous vous proposons des vibrateurs \u00e9lectriques \u00e0 moteur asynchrone triphas\u00e9, support\u00e9s par une robuste ossature et assembl\u00e9s pour une protection IP 65.7. Disponibles avec fixation \u00e0 plaque ou \u00e0 berceau. Les vibrateurs s\u00e9rie AFC et AFP \u00e0 haute fr\u00e9quence ou \u00e0 fr\u00e9quence de r\u00e9seau sont utilis\u00e9s sur les coffrages ou les tables vibrantes pour la r\u00e9alisation d\u2019\u00e9l\u00e9ments en b\u00e9ton  \u2022\u00a0ALIMENTATION TRIPHASEE  Sur demande, Bianchi Casseforme peut fournir le convertisseur de fr\u00e9quence ad\u00e9quat pour le fonctionnement de ses propres vibrateurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abcon.gr\/produit\/\u03b7\u03bb\u03b5\u03ba\u03c4\u03c1\u03b9\u03ba\u03bf\u03c3-\u03b4\u03bf\u03bd\u03b7\u03c4\u03b7\u03c3-\u03c5\u03c8\u03b7\u03bb\u03b7\u03c3-\u03c3\u03c5\u03c7\u03bd\u03bf\u03c4\u03b7\u03c4\u03b1\/\" \/>\n<meta property=\"og:site_name\" content=\"A.B.CON.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Steel.Precast.Solutions.ABCON\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abcon.gr\/wp-content\/uploads\/2018\/04\/High-frequency-electric-vibrator.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"180\" \/>\n\t<meta property=\"og:image:height\" content=\"135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/\",\"url\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/\",\"name\":\"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence - A.B.CON.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abcon.gr\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/High-frequency-electric-vibrator.jpg\",\"datePublished\":\"2018-04-03T07:42:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abcon.gr\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/High-frequency-electric-vibrator.jpg\",\"contentUrl\":\"https:\\\/\\\/abcon.gr\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/High-frequency-electric-vibrator.jpg\",\"width\":180,\"height\":135,\"caption\":\"High frequency electric vibrator\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abcon.gr\\\/produit\\\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1\",\"item\":\"https:\\\/\\\/abcon.gr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/\",\"name\":\"A.B.CON. - \u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 & \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2\",\"description\":\"\u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 &amp; \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2\",\"publisher\":{\"@id\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/#organization\",\"name\":\"A.B.CON. - \u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 & \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2\",\"url\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abcon.gr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_150.png\",\"contentUrl\":\"https:\\\/\\\/abcon.gr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_150.png\",\"width\":150,\"height\":74,\"caption\":\"A.B.CON. - \u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 & \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2\"},\"image\":{\"@id\":\"https:\\\/\\\/abcon.gr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Steel.Precast.Solutions.ABCON\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence - A.B.CON.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abcon.gr\/produit\/\u03b7\u03bb\u03b5\u03ba\u03c4\u03c1\u03b9\u03ba\u03bf\u03c3-\u03b4\u03bf\u03bd\u03b7\u03c4\u03b7\u03c3-\u03c5\u03c8\u03b7\u03bb\u03b7\u03c3-\u03c3\u03c5\u03c7\u03bd\u03bf\u03c4\u03b7\u03c4\u03b1\/","og_locale":"fr_FR","og_type":"article","og_title":"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence - A.B.CON.","og_description":"Sur les chantiers de pr\u00e9fabrication, pour obtenir une finition impeccable des \u00e9l\u00e9ments en b\u00e9ton \u00e0 r\u00e9sistance tr\u00e8s \u00e9lev\u00e9e, la vibration \u00e0 haute fr\u00e9quence est une n\u00e9cessit\u00e9 absolue. Nous vous proposons des vibrateurs \u00e9lectriques \u00e0 moteur asynchrone triphas\u00e9, support\u00e9s par une robuste ossature et assembl\u00e9s pour une protection IP 65.7. Disponibles avec fixation \u00e0 plaque ou \u00e0 berceau. Les vibrateurs s\u00e9rie AFC et AFP \u00e0 haute fr\u00e9quence ou \u00e0 fr\u00e9quence de r\u00e9seau sont utilis\u00e9s sur les coffrages ou les tables vibrantes pour la r\u00e9alisation d\u2019\u00e9l\u00e9ments en b\u00e9ton  \u2022\u00a0ALIMENTATION TRIPHASEE  Sur demande, Bianchi Casseforme peut fournir le convertisseur de fr\u00e9quence ad\u00e9quat pour le fonctionnement de ses propres vibrateurs.","og_url":"https:\/\/abcon.gr\/produit\/\u03b7\u03bb\u03b5\u03ba\u03c4\u03c1\u03b9\u03ba\u03bf\u03c3-\u03b4\u03bf\u03bd\u03b7\u03c4\u03b7\u03c3-\u03c5\u03c8\u03b7\u03bb\u03b7\u03c3-\u03c3\u03c5\u03c7\u03bd\u03bf\u03c4\u03b7\u03c4\u03b1\/","og_site_name":"A.B.CON.","article_publisher":"https:\/\/www.facebook.com\/Steel.Precast.Solutions.ABCON\/","og_image":[{"width":180,"height":135,"url":"https:\/\/abcon.gr\/wp-content\/uploads\/2018\/04\/High-frequency-electric-vibrator.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/","url":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/","name":"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence - A.B.CON.","isPartOf":{"@id":"https:\/\/abcon.gr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/#primaryimage"},"image":{"@id":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/abcon.gr\/wp-content\/uploads\/2018\/04\/High-frequency-electric-vibrator.jpg","datePublished":"2018-04-03T07:42:03+00:00","breadcrumb":{"@id":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/#primaryimage","url":"https:\/\/abcon.gr\/wp-content\/uploads\/2018\/04\/High-frequency-electric-vibrator.jpg","contentUrl":"https:\/\/abcon.gr\/wp-content\/uploads\/2018\/04\/High-frequency-electric-vibrator.jpg","width":180,"height":135,"caption":"High frequency electric vibrator"},{"@type":"BreadcrumbList","@id":"https:\/\/abcon.gr\/produit\/%ce%b7%ce%bb%ce%b5%ce%ba%cf%84%cf%81%ce%b9%ce%ba%ce%bf%cf%83-%ce%b4%ce%bf%ce%bd%ce%b7%cf%84%ce%b7%cf%83-%cf%85%cf%88%ce%b7%ce%bb%ce%b7%cf%83-%cf%83%cf%85%cf%87%ce%bd%ce%bf%cf%84%ce%b7%cf%84%ce%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/abcon.gr\/fr\/"},{"@type":"ListItem","position":2,"name":"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1","item":"https:\/\/abcon.gr\/shop\/"},{"@type":"ListItem","position":3,"name":"Vibrateurs \u00e9lectriques \u00e0 haute fr\u00e9quence"}]},{"@type":"WebSite","@id":"https:\/\/abcon.gr\/fr\/#website","url":"https:\/\/abcon.gr\/fr\/","name":"A.B.CON. - \u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 & \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2","description":"\u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 &amp; \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2","publisher":{"@id":"https:\/\/abcon.gr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abcon.gr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/abcon.gr\/fr\/#organization","name":"A.B.CON. - \u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 & \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2","url":"https:\/\/abcon.gr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/abcon.gr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/abcon.gr\/wp-content\/uploads\/2021\/04\/logo_150.png","contentUrl":"https:\/\/abcon.gr\/wp-content\/uploads\/2021\/04\/logo_150.png","width":150,"height":74,"caption":"A.B.CON. - \u039c\u03b7\u03c7\u03b1\u03bd\u03ad\u03c2 \u0395\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1\u03c2 \u03a3\u03ba\u03c5\u03c1\u03bf\u03b4\u03ad\u03bc\u03b1\u03c4\u03bf\u03c2 & \u03a0\u03c1\u03bf\u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae\u03c2"},"image":{"@id":"https:\/\/abcon.gr\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Steel.Precast.Solutions.ABCON\/"]}]}},"_links":{"self":[{"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/product\/8833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/media\/6518"}],"wp:attachment":[{"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/media?parent=8833"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/product_brand?post=8833"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/product_cat?post=8833"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/abcon.gr\/fr\/wp-json\/wp\/v2\/product_tag?post=8833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}